{"id":1904,"date":"2025-10-21T21:58:09","date_gmt":"2025-10-21T19:58:09","guid":{"rendered":"https:\/\/apcoruna.com\/?p=1904"},"modified":"2025-11-19T13:43:13","modified_gmt":"2025-11-19T12:43:13","slug":"a-asociacion-da-prensa-da-coruna-abre-a-convocatoria-do-lxxxv-premio-perez-lugin-dedicado-ao-150-aniversario-da-chegada-do-tren","status":"publish","type":"post","link":"https:\/\/apcoruna.com\/en\/a-asociacion-da-prensa-da-coruna-abre-a-convocatoria-do-lxxxv-premio-perez-lugin-dedicado-ao-150-aniversario-da-chegada-do-tren\/","title":{"rendered":"A APC abre a convocatoria do LXXXV Premio P\u00e9rez Lug\u00edn dedicado ao 150 aniversario da chegada do tren"},"content":{"rendered":"<p><span lang=\"GL\">A Asociaci\u00f3n da Prensa da Coru\u00f1a convoca a LXXXV edici\u00f3n do premio P\u00e9rez Lug\u00edn que nesta ocasi\u00f3n ten como lema: \u2018Do tren a Lugo ao AVE: 150 anos de ferrocarril na Coru\u00f1a\u2019.\u00a0<\/span><span lang=\"GL\">O 10 de outubro de 1875 sa\u00edu da Coru\u00f1a cara a Lugo o primeiro ferrocarril da historia da cidade. Os cronistas da \u00e9poca recolleron a noticia e desde ent\u00f3n os xornalistas informan das infraestruturas e as comunicaci\u00f3ns ferroviarias de Galicia. A Asociaci\u00f3n da Prensa da Coru\u00f1a s\u00famase a esta efem\u00e9ride co LXXXV Premio Alejandro P\u00e9rez Lug\u00edn, que este ano leva como lema \u201cDo tren a Lugo ao AVE: 150 anos de ferrocarril na Coru\u00f1a\u2019.<\/span><\/p>\n<p><span lang=\"GL\">Con motivo desta importante efem\u00e9ride queremos desde a Asociaci\u00f3n da Prensa da Coru\u00f1a sumarnos \u00e1s celebraci\u00f3ns dedic\u00e1ndolle tam\u00e9n noso premio anual Alejandro P\u00e9rez Lug\u00edn. Os interesados poder\u00e1n enviar os seus escritos ata o vindeiro 30 de novembro. Tr\u00e1tase dunha convocatoria aberta, pero soamente poder\u00e1n presentar un traballo, enmarcado en calquera x\u00e9nero period\u00edstico. Os traballos deber\u00e1n ser in\u00e9ditos e estar escritos indistintamente en galego ou castel\u00e1n, cunha extensi\u00f3n m\u00e1xima de 5.100 caracteres.<\/span><\/p>\n<p><b><span lang=\"GL\">Presentaci\u00f3n dos traballos<\/span><\/b><\/p>\n<p><span lang=\"GL\">As obras deber\u00e1n ser enviadas en papel por correo certificado e en soporte inform\u00e1tico (formato Word ou PDF), \u00e1 Asociaci\u00f3n da Prensa da Coru\u00f1a, en sobre pechado e ao seguinte enderezo C\/ Dur\u00e1n Loriga, 10-4. 15003, A Coru\u00f1a.<\/span><\/p>\n<p><span lang=\"GL\">O sobre levar\u00e1 un seud\u00f3nimo en galego, un lema e a indicaci\u00f3n \u201cPremio P\u00e9rez Lug\u00edn\u201d. No interior ir\u00e1 un segundo sobre, c\u00f3 lema e o seud\u00f3nimo do exterior, no que se incluir\u00e1n os datos do autor (nome e apelidos, enderezo y tel\u00e9fono de contacto) e un breve curr\u00edculum.<\/span><\/p>\n<p><span lang=\"GL\">Os traballos tam\u00e9n poder\u00e1n ser enviados por mail cun enderezo electr\u00f3nico creado co seud\u00f3nimo baixo o que se presenta o autor e co mesmo lema no asunto. O autor non debe identificarse de ning\u00fan modo ou o traballo quedar\u00e1 automaticamente eliminado.<\/span><\/p>\n<p><span lang=\"GL\">O env\u00edo do mail non exime de remitir o sobre co traballo en papel cos correspondentes sobres que si identifican ao autor.<\/span><\/p>\n<p><span lang=\"GL\">O premio para o traballo ga\u00f1ador ser\u00e1 unha figura de Sargadelos, as\u00ed como 3.000 euros. O acto de entrega ao galardoado ser\u00e1 no no Concello da Coru\u00f1a, entidade que a s\u00faa vez colabora na realizaci\u00f3n desta convocatoria.<\/span><\/p>\n<p><span lang=\"GL\">\u00a0<\/span><b><span lang=\"GL\">Historial do P\u00e9rez Lug\u00edn<\/span><\/b><\/p>\n<p><span lang=\"GL\">En 2025 o Premio P\u00e9rez Lug\u00edn acada a s\u00faa edici\u00f3n n\u00famero 85. En 1936, a vi\u00fava do xenial escritor da Casa da Troya creou unha fundaci\u00f3n co nome do seu marido, dot\u00e1ndoa dun capital, depositado no Banco Pastor, con cuxos intereses deber\u00eda concederse o premio, segundo rezaba textualmente \u201cao mellor traballo literario que se presente sobre un tema de Galicia enxalzando a mesma\u201d. Posteriormente, no 1941, creouse o premio e o ga\u00f1ador da primeira edici\u00f3n foi Eduardo P\u00e9rez Hervada. Desde ent\u00f3n obtiv\u00e9rono destacados xornalistas e escritores. A listaxe incl\u00fae a Ezequiel P\u00e9rez Montes (1963), Emilio Quesada (1964) ou \u00c1ngel Pad\u00edn (1999).<\/span><\/p>\n<p><span lang=\"GL\">Nos \u00faltimos anos, os ga\u00f1adores foron Rodri Su\u00e1rez (2019), Suso Mart\u00ednez (2020), Javier Quintana (en 2021, a\u00ednda que tam\u00e9n o ga\u00f1ou en 2009), Xavier Lama (2022), Toni Silva (2023) e Ricardo F. Colmenero (2024). A primeira muller galardoada co P\u00e9rez Lug\u00edn foi Mercedes Modro\u00f1o (1989), \u00e1 que sucederon Cristina Amenedo (1995), Lola Roel (1996) e Mar\u00eda del Rosario Mart\u00ednez Mart\u00ednez (2007).<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>BASES DO CONCURSO:\u00a0 \u00a0<\/strong><strong>LXXXV PREMIO \u201cALEJANDRO P\u00c9REZ LUG\u00cdN 2025\u201d DE XORNALISMO<\/strong><\/p>\n<p>A Asociaci\u00f3n da Prensa da Coru\u00f1a, co patrocinio do Excelent\u00edsimo Concello da Coru\u00f1a, convoca a LXXXV edici\u00f3n do Premio \u201cAlejandro P\u00e9rez Lug\u00edn\u201d, de xornalismo, conforme as seguintes Bases:<\/p>\n<p><strong>1.-<\/strong> Poder\u00e1n participar no <strong>Premio Xornal\u00edstico Alejandro P\u00e9rez Lug\u00edn<\/strong> correspondente ao ano 2025 cantas persoas des\u00e9xeno, coa condici\u00f3n de que cada concursante s\u00f3 poder\u00e1 presentar un traballo encadrado en calquera x\u00e9nero xornal\u00edstico.<\/p>\n<p><strong>2.-<\/strong> A dotaci\u00f3n do Premio \u00e9 de 3.000 euros. O galard\u00f3n estar\u00e1 suxeito \u00e1 normativa fiscal vixente no momento da s\u00faa entrega.<\/p>\n<p><strong>3.-<\/strong> O tema central dos traballos que opten ao Premio versar\u00e1 sobre <strong>Do tren a Lugo ao AVE: 150 anos de ferrocarril na Coru\u00f1a<\/strong> e estar\u00e1 dedicado \u00e1 chegada do tren \u00e1 Coru\u00f1a, que en 2025 cumpre 150.<\/p>\n<p><strong>4.-<\/strong> Os traballos poder\u00e1n ser presentados en galego ou en castel\u00e1n.<\/p>\n<p><strong>5.-<\/strong> Os traballos presentados ser\u00e1n in\u00e9ditos e ter\u00e1n unha extensi\u00f3n m\u00e1xima de tres folios ou 5.100 caracteres.<\/p>\n<p><strong>6.-<\/strong> Remitiranse, por correo certificado, nun sobre pechado \u00e1 seguinte direcci\u00f3n: <strong>Asociaci\u00f3n da Prensa da Coru\u00f1a\u201d. C\/ Dur\u00e1n Loriga, 10- 4\u00ba. 15003- A Coru\u00f1a.<\/strong> O sobre levar\u00e1 un<strong> pseud\u00f3nimo e un lema e a indicaci\u00f3n \u201cPremio Alejandro P\u00e9rez Lug\u00edn\u201d.<\/strong> Igualmente, dentro deste sobre incorporarase outro m\u00e1is pequeno no que, no seu exterior, figurar\u00e1 o lema. Dentro deste incluiranse os datos do autor (nome e apelidos, direcci\u00f3n, tel\u00e9fono de contacto) e un breve curriculum profesional.<\/p>\n<p><strong>7.-<\/strong> Os traballos remitiranse en orixinal triplicado e acompa\u00f1aranse dunha copia en soporte inform\u00e1tico (formato word). Tam\u00e9n se poder\u00e1n enviar os traballos a trav\u00e9s dun correo electr\u00f3nico creado co pseud\u00f3nimo baixo o que se presenta o autor e co mesmo lema. De ning\u00fan xeito poder\u00e1 identificarse \u00e1 persoa que se presenta a trav\u00e9s do correo electr\u00f3nico ou o traballo quedar\u00e1 automaticamente eliminado. O env\u00edo do correo electr\u00f3nico non exime do env\u00edo co traballo en papel e, no seu interior, o sobre pechado cos datos persoais, que debe ser enviado de forma f\u00edsica \u00e1 direcci\u00f3n postal da asociaci\u00f3n.<\/p>\n<p><strong>8.-<\/strong> O prazo de recepci\u00f3n de orixinais finalizar\u00e1 o <strong>30 de novembro de 2025<\/strong> (para os efectos de recepci\u00f3n terase en conta a data do cu\u00f1o).<\/p>\n<p><strong>9.-<\/strong> O Xurado estar\u00e1 composto pola Xunta Directiva da Asociaci\u00f3n da Prensa da Coru\u00f1a, un representante do Concello da Coru\u00f1a e o ga\u00f1ador da \u00faltima edici\u00f3n do \u201cP\u00e9rez Lug\u00edn\u201d.<\/p>\n<p><strong>10.-<\/strong> Ser\u00e1 Presidenta do Xurado a da Asociaci\u00f3n da Prensa da Coru\u00f1a (ou persoa en quen delegue). A secretaria da mesma actuar\u00e1 tam\u00e9n como secretaria de actas, con voz e voto.<\/p>\n<p><strong>11.-<\/strong> Quedan exclu\u00eddos de participar nesta convocatoria todos e cada un dos integrantes do Xurado.<\/p>\n<p><strong>12.-<\/strong> O Xurado emitir\u00e1 o seu fallo antes do 25 de decembro de 2025 e o Premio ser\u00e1 entregado no transcurso dun acto que ter\u00e1 lugar con motivo da celebraci\u00f3n da festividade de San Francisco de Sales, Patr\u00f3n dos xornalistas, no sal\u00f3n de plenos do Concello. Ser\u00e1 requisito imprescindible a asistencia ao mesmo do premiado.<\/p>\n<p><strong>13.-<\/strong> A Asociaci\u00f3n da Prensa da Coru\u00f1a res\u00e9rvase o dereito de reproducir o traballo ga\u00f1ador ou, se as\u00ed o estimase, unha selecci\u00f3n ou a totalidade de cuantos pres\u00e9ntense ao Premio.<\/p>\n<p><strong>14.-<\/strong> O Xurado resolver\u00e1 en cuantos aspectos non contemplados nestas bases xurdan ao longo do proceso de concesi\u00f3n do Premio.<\/p>\n<p><strong>15.-<\/strong> A participaci\u00f3n neste certame implica a aceptaci\u00f3n das bases, polo que o veredicto do Xurado ser\u00e1 inapelable.<\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>O prazo de presentaci\u00f3n de traballos queda aberto ata o 30 de novembro. O galard\u00f3n conta cunha dotaci\u00f3n de 3.000 euros, que aporta o Concello da Coru\u00f1a. <\/p>","protected":false},"author":3,"featured_media":1905,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25,8],"tags":[37,42,30],"class_list":["post-1904","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-premios","tag-apc","tag-perez-lugin","tag-premios"],"_links":{"self":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/1904","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/comments?post=1904"}],"version-history":[{"count":4,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/1904\/revisions"}],"predecessor-version":[{"id":1934,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/1904\/revisions\/1934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/media\/1905"}],"wp:attachment":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/media?parent=1904"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/categories?post=1904"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/tags?post=1904"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}