{"id":745,"date":"2024-01-27T11:33:17","date_gmt":"2024-01-27T10:33:17","guid":{"rendered":"https:\/\/apcoruna.com\/?p=745"},"modified":"2024-04-30T21:11:29","modified_gmt":"2024-04-30T19:11:29","slug":"a-apc-entrega-no-concello-da-coruna-o-premio-perez-lugin-a-toni-silva","status":"publish","type":"post","link":"https:\/\/apcoruna.com\/en\/a-apc-entrega-no-concello-da-coruna-o-premio-perez-lugin-a-toni-silva\/","title":{"rendered":"A APC entrega no Concello da Coru\u00f1a o premio P\u00e9rez Lug\u00edn a Toni Silva"},"content":{"rendered":"<p>A presidenta da Asociaci\u00f3n da Prensa da Coru\u00f1a, Doda V\u00e1zquez, entregou este venres 26 de xaneiro o premio da LXXXIII edici\u00f3n do premio P\u00e9rez Lug\u00edn a Toni Silva polo seu traballo \u201cCr\u00f3nica negra a mil pulsaciones y dos pulgares\u201d. O acto, celebrado no sal\u00f3n de sesi\u00f3ns do Concello da Coru\u00f1a, estivo presidido pola alcaldesa da cidade, In\u00e9s Rey.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-747\" src=\"https:\/\/apcoruna.com\/wp-content\/uploads\/2024\/01\/1APG7427-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p>Durante o acto de entrega, a presidenta da Asociaci\u00f3n da Prensa da Coru\u00f1a, destacou que \u201ceste premio xa \u00e9 un dos m\u00e1is antigos de Espa\u00f1a\u201d, ao tempo que lembrou que nesta edici\u00f3n ti\u00f1a o m\u00f3bil como referente \u00e9 sobre isto dixo: \u201cTen transformado profundamente a vida dos xornalistas pero se hai unha profesi\u00f3n que vive permanentemente no arame da d\u00fabida e do cambio constante \u00e9 precisamente a nosa, na que, cando a p\u00e1xina ou a cr\u00f3nica esta lista e enviada, as veces hai que cambiala unha vez m\u00e1is\u00bb.<\/p>\n<p>\u00abNestes tempos nos que a inmediatez choca coa verificaci\u00f3n, a primicia co posicionamento e o traballo diario coa tiran\u00eda de<br \/>\nGoogle, aparecen novos desaf\u00edos como a intelixencia artificial. Non sei como ser\u00e1n os vindeiros 120 anos, pero seguro que haber\u00e1 alg\u00fan xornalista para que o conte\u201d, rematou.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-748\" src=\"https:\/\/apcoruna.com\/wp-content\/uploads\/2024\/01\/1APG7554-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><br \/>\n<strong>O ga\u00f1ador<\/strong><br \/>\nToni Silva, xornalista de La Voz de Galicia desde hai case tres d\u00e9cadas, destacou na s\u00faa intervenci\u00f3n: \u201c\u00c9 un orgullo formar parta da lista de xornalistas aos que admiro, e recibir o reco\u00f1ecemento dos teus compa\u00f1eiros de profesi\u00f3n\u201d ao que engadiu que \u201cAgrad\u00e9zolle p\u00fablicamente ao xurado deste premio haber seleccionado o meu artigo e ao Concello da Coru\u00f1a por continuar apoiando un dos certames decanos de Espa\u00f1a\u201d.<\/p>\n<p>Silva falou do seu traballo no diario e, especialmente, na redacci\u00f3n de Local da Coru\u00f1a, onde mencionou a alg\u00fans dos seus compa\u00f1eiros, moitos deles presentes, como unha \u00abgran familia\u00bb, cunha lembranza para delegados como Laureano L\u00f3pez, Francisco Espi\u00f1eira ou Alfonso Andrade e unha homenaxe especial para aqueles \u00abimprescindibles\u00bb que lle fan a vida m\u00e1is doada aos demais e que sempre est\u00e1n para axudar, como Rosa Dom\u00ednguez, para a que pediu un gran aplauso que os asistentes non dubidaron en secundar.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-749\" src=\"https:\/\/apcoruna.com\/wp-content\/uploads\/2024\/01\/1APG7503-300x200.jpg\" alt=\"\" width=\"300\" height=\"200\" \/><\/p>\n<p>No seu discurso, In\u00e9s Rey lembrou que a invenci\u00f3n do tel\u00e9fono m\u00f3bil cambiou a forma de ver a vida e tam\u00e9n de traballar. \u00abNingu\u00e9n pode entender a nosa sociedade sen a conexi\u00f3n que nos facilita a tecnolox\u00eda\u00bb, explicou, destacando os beneficios do m\u00f3bil como ferramenta, tam\u00e9n para os xornalistas e trasladou os parab\u00e9ns a toda a comunidade a trav\u00e9s do ga\u00f1ador do premio.<\/p>","protected":false},"excerpt":{"rendered":"<p>A presidenta da Asociaci\u00f3n da Prensa da Coru\u00f1a, Doda V\u00e1zquez, entregou este venres 26 de xaneiro o premio da LXXXIII edici\u00f3n do premio P\u00e9rez Lug\u00edn a Toni Silva polo seu traballo \u201cCr\u00f3nica negra a mil pulsaciones y dos pulgares\u201d. O acto, celebrado no sal\u00f3n de sesi\u00f3ns do Concello da Coru\u00f1a, estivo presidido pola alcaldesa da [&hellip;]<\/p>","protected":false},"author":3,"featured_media":746,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25,8],"tags":[22],"class_list":["post-745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","category-premios","tag-premio-perez-lugin"],"_links":{"self":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/comments?post=745"}],"version-history":[{"count":4,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/745\/revisions"}],"predecessor-version":[{"id":755,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/745\/revisions\/755"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/media\/746"}],"wp:attachment":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/media?parent=745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/categories?post=745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/tags?post=745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}