{"id":928,"date":"2024-04-14T14:02:57","date_gmt":"2024-04-14T12:02:57","guid":{"rendered":"https:\/\/apcoruna.com\/?p=928"},"modified":"2024-04-30T21:08:15","modified_gmt":"2024-04-30T19:08:15","slug":"a-apc-convoca-o-ix-concurso-de-debuxo-picasso-para-alumnado-de-primaria-e-eso-de-galicia","status":"publish","type":"post","link":"https:\/\/apcoruna.com\/en\/a-apc-convoca-o-ix-concurso-de-debuxo-picasso-para-alumnado-de-primaria-e-eso-de-galicia\/","title":{"rendered":"A APC convoca o IX Concurso de Debuxo Picasso para alumnado de Primaria e ESO de Galicia"},"content":{"rendered":"<p class=\"p1\"><span class=\"s1\">A<\/span> Asociaci\u00f3n da Prensa da Coru\u00f1a (APC) convoca o IX Concurso de Debuxo Picasso co patrocinio da Conseller\u00eda de Cultura, Educaci\u00f3n, FP e Universidades da Xunta de Galicia e coa colaboraci\u00f3n do IES Pluriling\u00fce Eusebio da Guarda.<\/p>\n<p class=\"p1\">O certame, dirixido ao alumnado de 3\u00ba a 6\u00ba de Primaria e de ESO de toda Galicia, pretende estimular a creatividade do estudantado e resaltar a figura do pintor na s\u00faa etapa na cidade herculina, anos que foron especialmente relevantes no desenvolvemento do talento creativo de Picasso.<\/p>\n<p class=\"p1\">Os traballos ga\u00f1adores exporanse no IES Plu<span class=\"s1\">riling\u00fce <\/span>Eusebio da Guarda, o instituto no que o xenial artista estudou Belas Artes e ensino secundario entre os anos 1891 e 1895.<\/p>\n<p class=\"p1\">Durante a s\u00faa estancia na Coru\u00f1a, o adolescente Picasso elaborou xornais de tama\u00f1o folio nos que combinaba textos e debuxos. Bautizounos como \u201cAzul y Blanco\u201d e \u201cLa Coru\u00f1a\u201d. Os participantes no presente concurso te\u00f1en que emular estes xornais, pero cun contido actual.<\/p>\n<p class=\"p1\">A iniciativa est\u00e1 aberta \u00e1 participaci\u00f3n do alumnado dos centros p\u00fablicos, concertados e privados de toda Galicia de 3\u00ba a 6\u00ba de Primaria e da ESO. A data l\u00edmite para enviar os traballos \u00e1 APC (r\u00faa Dur\u00e1n Loriga, 10. 15003. A Coru\u00f1a) remata o 31 de maio de 2024 e o xurado dar\u00e1 a co\u00f1ecer a s\u00faa resoluci\u00f3n no mes de xu\u00f1o.<\/p>\n<p class=\"p1\">Haber\u00e1 tres premios por categor\u00eda: Premio Picasso ao mellor xornal. Premio Jos\u00e9 Luis Bugallal Marchesi \u00e1 mellor ilustraci\u00f3n e Premio Olga Cristina Via\u00f1o S\u00e1nchez a mellor redacci\u00f3n. Ademais, distinguiranse con acc\u00e9sit un m\u00ednimo de 5 obras de cada unha das categor\u00edas.<\/p>\n<p class=\"p1\">Os ga\u00f1adores de cada unha das tres categor\u00edas do Premio Picasso ao mellor xornal recibir\u00e1n un cheque regalo de 450 euros e os tres profesores que enviaron os traballos ga\u00f1adores, un lector de libro electr\u00f3nico.<\/p>\n<p class=\"p1\">Pola s\u00faa banda, os ga\u00f1adores dos premios Jos\u00e9 Luis Bugallal Marchesi e Olga Cristina Via\u00f1o S\u00e1nchez en cada unha das tres categor\u00edas recibir\u00e1n un cheque regalo por valor de 300 euros.<\/p>\n<p class=\"p1\">Os participantes distinguidos con acc\u00e9sit recibir\u00e1n un diploma acreditativo.<\/p>\n<p class=\"p1\"><a href=\"https:\/\/apcoruna.com\/wp-content\/uploads\/2024\/04\/picasso_horizontal.pdf\">As bases do IX Concurso<\/a> de Debuxo Picasso poden consultarse na web da <span class=\"s3\">Asociaci\u00f3n da Prensa da Coru\u00f1a <\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>A Asociaci\u00f3n da Prensa da Coru\u00f1a (APC) convoca o IX Concurso de Debuxo Picasso co patrocinio da Conseller\u00eda de Cultura, Educaci\u00f3n, FP e Universidades da Xunta de Galicia e coa colaboraci\u00f3n do IES Pluriling\u00fce Eusebio da Guarda. O certame, dirixido ao alumnado de 3\u00ba a 6\u00ba de Primaria e de ESO de toda Galicia, pretende [&hellip;]<\/p>","protected":false},"author":3,"featured_media":929,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[25],"tags":[24,23],"class_list":["post-928","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destacadas","tag-conselleria-de-cultura","tag-picasso"],"_links":{"self":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/928","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/comments?post=928"}],"version-history":[{"count":4,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/928\/revisions"}],"predecessor-version":[{"id":934,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/posts\/928\/revisions\/934"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/media\/929"}],"wp:attachment":[{"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/media?parent=928"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/categories?post=928"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apcoruna.com\/en\/wp-json\/wp\/v2\/tags?post=928"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}